{"id":1816,"date":"2014-05-20T22:39:25","date_gmt":"2014-05-20T22:39:25","guid":{"rendered":"http:\/\/www.imer.mx\/xeb\/?page_id=1816"},"modified":"2014-05-24T00:15:57","modified_gmt":"2014-05-24T00:15:57","slug":"xeb-nueve-decadas-de-historia-con-mayusculas","status":"publish","type":"page","link":"https:\/\/www.imer.mx\/xeb\/xeb-nueve-decadas-de-historia-con-mayusculas\/","title":{"rendered":"XEB, nueve d\u00e9cadas de historia con may\u00fasculas"},"content":{"rendered":"<p><strong>El inicio<\/strong><\/p>\n<p>El 16 de junio de 1923, se inaugur\u00f3 la Primera Feria Internacional de la Radio, promovida por la Liga Central Mexicana de Radio, para mostrar al p\u00fablico los beneficios de una industria naciente. Como actividad promocional, la Compa\u00f1\u00eda Cigarrera del Buen Tono, S. A., lanz\u00f3 a la venta una marca de cigarrillos \u201cRadio\u201d y durante ese mismo mes, iniciaron las transmisiones de prueba de la Estaci\u00f3n Radiotelef\u00f3nica del Buen Tono (CYB).<\/p>\n<p>El 14 de septiembre de 1923, se llev\u00f3 cabo la primera transmisi\u00f3n en forma, consistente en la narrativa de la pelea sostenida por los boxeadores Luis \u00c1ngel Firpo \u201cEl toro de las pampas\u201d y Jack Depmsey, en el Estadio Polo Grounds de Nueva York. El radioaficionado Jos\u00e9 Velasco captaba en Pachuca la se\u00f1al de la emisora neoyorquina y proporcionaba los datos que a su vez eran comentados por Enrique W. Curtiss, en los micr\u00f3fonos de CYB.<\/p>\n<p>El 15 de septiembre de 1923, la Estaci\u00f3n del Buen Tono realiz\u00f3 su concierto inaugural, con discursos del coronel Jos\u00e9 Fernando Ram\u00edrez, el doctor Antonio Mart\u00ednez Cu\u00e9tara y una serie de canciones asturianas interpretadas por el Coro Astur, Manuel P\u00e9rez \u201cManol\u00edn\u201d y Ramon\u00edn Rionda. Tambi\u00e9n se transmiti\u00f3 un mensaje del rey Alfonso XIII de Espa\u00f1a a las naciones americanas, utiliz\u00e1ndose un disco fonogr\u00e1fico grabado por el monarca.<\/p>\n<p>En octubre de 1923, en vista del \u00e9xito obtenido, CYB decidi\u00f3 transmitir todos los martes, jueves y s\u00e1bados, de 20:00 a 21:00 horas, bajo la direcci\u00f3n art\u00edstica del pianista Manuel Barajas.<\/p>\n<p>El primer gerente de la Radiodifusora del Buen Tono fue el ingeniero Jos\u00e9 J. Reynoso, uno de los diputados constituyentes que firmaron la Carta Magna el 5 de febrero de 1917; despu\u00e9s, tuvo el cargo de senador en la XXVII Legislatura y posteriormente estuvo ligado a los gobiernos de \u00c1lvaro Obreg\u00f3n y Plutarco El\u00edas Calles. Falleci\u00f3 el 17 de junio de 1945. Quien realiz\u00f3 el trabajo de montaje de la emisora durante 1923, fue el ingeniero Jos\u00e9 de la Herr\u00e1n Pau, con la colaboraci\u00f3n de Guillermo Garc\u00eda Ramos.<\/p>\n<p>A finales de 1923, se efectu\u00f3 en CYB el primer reportaje taurino radiof\u00f3nico, realizado por el anunciador Jorge Marr\u00f3n y el cronista \u201cCurro Faroles\u201d. Un a\u00f1o despu\u00e9s, se realiz\u00f3 el primer control remoto taurino, desde la Plaza de Toros El Toreo (ubicado en la colonia Condesa), en el que particip\u00f3 Enrique Arizmendi, narrando la faena del matador Manuel Mart\u00ednez \u201cChicuelo\u201d.<\/p>\n<p><strong>Las nuevas nominales y la segunda d\u00e9cada de actividades<\/strong><\/p>\n<p>Las nominales CYB de la Emisora del Buen Tono se asignaron oficialmente en julio de 1924, durante la Conferencia Internacional de Comunicaciones celebrada en Berna (aunque existen documentos que demuestran que se utilizaron desde su inauguraci\u00f3n en 1923). A M\u00e9xico le correspondieron las siglas CYA a CZZ, de ah\u00ed que Jos\u00e9 J. Reynoso solicit\u00f3 oficialmente dichas letras como nominales. A\u00f1os despu\u00e9s, en 1929, durante la Conferencia Internacional de Comunicaciones, celebrada en la ciudad de Washington, D. C., se le otorgaron las siglas \u201cXEB\u201d. Desde ese momento, han permanecido inalterables hasta nuestros d\u00edas.<\/p>\n<p>En 1929, la actriz Pura C\u00f3rdoba form\u00f3 en XEB el cuadro dram\u00e1tico \u201cEugenia Torres\u201d, con otros destacados actores. Este trabajo sent\u00f3 las bases de la radionovela en M\u00e9xico, que constituy\u00f3 uno de los conceptos m\u00e1s exitosos de la radio nacional. Para febrero de 1930, hab\u00eda 32 estaciones en todo el pa\u00eds; dos a\u00f1os despu\u00e9s, se contabilizaban 55. En ese momento, XEB se ubicaba en los 665 kilohertz de la banda de Amplitud Modulada.<\/p>\n<p>Durante los primeros a\u00f1os de la Emisora del Buen Tono, se crearon muchos conceptos y f\u00f3rmulas que rigen hasta nuestros d\u00edas el quehacer radiof\u00f3nico en general. Pioneros en sus micr\u00f3fonos, fueron: Jorge Marr\u00f3n (el que despu\u00e9s se convirtiera en el famoso Doctor IQ) y Enrique W. Curtiss. En el lapso de 1930 a 1940, la emisora estuvo identificada por los locutores: Humberto G. Tamayo, Joaqu\u00edn Gamboa, Edmundo Garc\u00eda, Adri\u00e1n Fournier, Guillermo N\u00fa\u00f1ez Keith y Oscar Pulido, entre otros. En 1933, Julio Sotelo inici\u00f3 sus labores como anunciador de la estaci\u00f3n; con el paso de los a\u00f1os, fue considerado el mejor cronista deportivo, incluso particip\u00f3 en varias pel\u00edculas, narrando peleas de box y de lucha libre.<\/p>\n<p><strong>Artistas forjados por la Emisora del Buen Tono<\/strong><\/p>\n<p>En 1929, el entonces desconocido compositor Agust\u00edn Lara y su int\u00e9rprete Maruca P\u00e9rez participaron en un programa radiof\u00f3nico de prueba en XEB; el anunciador fue Jorge Marr\u00f3n. Al terminar su actuaci\u00f3n, como pago recibieron una polvera esmaltada y un paquete de cigarros \u201cCanela pura\u201d, fabricados por el Buen Tono, S. A.<\/p>\n<p>De 1930 a 1940, XEB fue crisol de nuevos valores en la m\u00fasica popular. En este lapso, figuraron como int\u00e9rpretes exclusivos: Margarita Romero, las Hermanas Land\u00edn (Avelina y Mar\u00eda Luisa), el Dr. Alfonso Ortiz Tirado, Antonio Escobar, Vicente Bergmann, las hermanas Ruiz Armengol, Raquel Moreno, Dora Luz, Maruca P\u00e9rez, Wello Rivas, Carlos de Nava, Enrique Quezada, Alberto Cervantes, Jaime Nolla Reyes, N\u00e9stor Mesta Chayres, Manuel Esper\u00f3n, Miguel Prado y muchos m\u00e1s.<\/p>\n<p>En 1931, se present\u00f3 en XEB la compa\u00f1\u00eda art\u00edstica cubana de Ernesto Lecuona, integrada por Absal\u00f3n P\u00e9rez, Rita Montaner, Bola de Nieve y el propio compositor. Este grupo trajo consigo una nueva f\u00f3rmula para la m\u00fasica tropical.<\/p>\n<p>En agosto de 1933, despu\u00e9s de un exitoso programa de prueba con Ernesto Riestra y su jazz band, se cre\u00f3 el primer espacio musical de 60 minutos en la radio mexicana; fue transmitido de lunes a viernes con el t\u00edtulo \u201cT\u00e9 para dos\u201dm que tiempo despu\u00e9s se denomin\u00f3 \u201cPicadillo musical\u201d. En ese a\u00f1o, El Buen Tono inaugur\u00f3 su emisora en Onda Corta, con nominales XEBT, ubicada en los 6000 kilociclos, con lo que lleg\u00f3 su se\u00f1al a todo el mundo. Gracias a su destacada labor, artistas de la talla de Alfonso Ortiz Tirado y Miguel Prado, lograron importantes contrataciones en varios pa\u00edses de Sudam\u00e9rica.<\/p>\n<p>El 28 de octubre de 1934, ya ubicada en los 1030 kilociclos de onda larga, XEB inaugur\u00f3 nuevos estudios de transmisi\u00f3n, situados en el inmueble de Buen Tono 6. El ingeniero Walter Cross Buchanan fue responsable t\u00e9cnico de la emisora desde mediados de los a\u00f1os treinta, posici\u00f3n que mantuvo por muchos a\u00f1os, alternando sus actividades acad\u00e9micas como creador de la especialidad de ingenier\u00eda electr\u00f3nica en la ESIME del IPN.<\/p>\n<p>En 1936, el compositor puertorrique\u00f1o Rafael Hern\u00e1ndez fue contratado para participar en los Programas Picot de XEB. El \u00e9xito de esta serie musical, propici\u00f3 que la radiodifusora inaugurara un nuevo teatro-estudio en sus instalaciones, para dar cabida a los numerosos espectadores. En estas audiciones, destac\u00f3 la trilog\u00eda art\u00edstica integrada por los cantantes Margarita Romero, Wello Rivas y el propio Rafael, con sus canciones y su orquesta. Hacia 1937, participaba como guitarrista de esta agrupaci\u00f3n el talentoso Alfredo \u201cEl g\u00fcero\u201d Gil, quien a\u00f1os m\u00e1s tarde, en 1944, con Chucho Navarro (tambi\u00e9n artista de XEB en sus inicios) form\u00f3 el Tr\u00edo Los Panchos.<\/p>\n<p>Otra figura art\u00edstica s\u00f3lidamente ligada a la historia de XEB, fue sin duda Pedro Infante. Todo sucedi\u00f3 as\u00ed: en 1938, solicit\u00f3 una prueba como cantante y fue aceptado para canta en programas de quince minutos, cada tercer d\u00eda, ganando 200 pesos al mes; esto le permiti\u00f3 vivir con cierta holgura. Atestiguaron este hecho, el maestro Ernesto Belloc, pianista que le hizo la prueba de voz, adem\u00e1s de los operadores Luis Prud\u00f3n y Raciel L\u00f3pez Varela.<\/p>\n<p><strong>Los vientos de guerra provocaron cambios.<\/strong><\/p>\n<p>Entre 1942 y 1946, la emisora del Buen Tono transmiti\u00f3 dos noticiarios de gran importancia: \u201cNoticiero Mundial\u201d y \u201cEl o\u00eddo del mundo\u201d. Esta actividad fue reflejo del conflicto b\u00e9lico en Europa, lo que provoc\u00f3 una competencia entre las emisoras del cuadrante para entregar la noticia m\u00e1s reciente.<\/p>\n<p>El 12 de octubre de 1942, XEB anunci\u00f3 la inauguraci\u00f3n de sus nuevas oficinas, dos teatros para conciertos musicales, cinco nuevos estudios y un teletipo permanentemente conectado a la United Press. Tambi\u00e9n, se coment\u00f3 el establecimiento de una cadena de cuarenta emisoras en todo el territorio nacional, y la instauraci\u00f3n de un departamento especializado de producci\u00f3n y otro de \u201cpublicidad especial\u201d. Se inform\u00f3 del incremento en la potencia, a 100,000 watts. Sin embargo, debido al desabasto de refacciones en su planta transmisora, a causa de la Segunda Guerra Mundial, la emisora curs\u00f3 una etapa con graves problemas t\u00e9cnicos.<\/p>\n<p>El 15 de junio de 1944, despu\u00e9s de permanecer 11 a\u00f1os en la gerencia de XEB, Bernardo Sancrist\u00f3bal dej\u00f3 el puesto, siendo ocupado por Manuel Gonz\u00e1lez Calzada hasta el 30 de noviembre del mismo a\u00f1o. El 16 de septiembre de aquel 1944, XEB fue declarada \u201cCiudadana del aire\u201d; el entonces Secretario de Educaci\u00f3n Jaime Torres Bodet estuvo presente en el Estudio Juventino Rosas para pronunciar un discurso en el que resalt\u00f3 el papel de la emisora como un elemento valioso para la vida de los mexicanos.<\/p>\n<p>En diciembre de 1944, Andr\u00e9 Duprat Pugibet, due\u00f1o de la Cigarrera del Buen Tono y de XEB, llam\u00f3 al maestro Armando de Maria y Campos para la gerencia de la emisora. En ese tiempo, se retir\u00f3 la actriz Pura C\u00f3rdoba, quien desde 1929 manejaba el cuadro de actores \u201cEugenia Torres\u201d, encargado de realizar radioteatros dominicales. Entonces, se procedi\u00f3 a la contrataci\u00f3n de Virginia F\u00e1bregas, Esperanza Iris y Gloria Iturbe, destacadas actrices de la escena teatral. Esto le dio a XEB una gran oportunidad para transmitir dramatizaciones de gran calidad, a trav\u00e9s del \u201cTeatro del Aire\u201d. Tambi\u00e9n participaron los dramaturgos Xavier Villaurrutia y Luis G. Basurto.<\/p>\n<p>En abril de 1945, la \u201cB\u201d tuvo el orgullo de ser la primera estaci\u00f3n del pa\u00eds en informar de la s\u00fabita muerte del mandatario estadounidense Franklin Delano Roosevelt, anticip\u00e1ndose por 4 minutos al informe que dieron las estaciones de la competencia: XEQ, XEW y Radio Mil.<\/p>\n<p>En 1945, XEB cre\u00f3 una cadena radiof\u00f3nica para la transmisi\u00f3n de eventos deportivos, proyecto para el que se contrat\u00f3 a futuros personajes de la cr\u00f3nica, como: Fernando Marcos, Cristino Lorenzo, Agust\u00edn Gonz\u00e1lez \u201cEscopeta\u201d, y reafirm\u00f3 la presencia de Julio Sotelo, quien por su peculiar estilo narrativo, ten\u00eda muchos seguidores.<\/p>\n<p><strong>Los nuevos cambios.<\/strong><\/p>\n<p>A partir de 1946, la programaci\u00f3n de XEB fue despoj\u00e1ndose de sus emisiones con artistas en \u201cvivo\u201d, para volverse disquera, lo cual resultaba m\u00e1s funcional y econ\u00f3mico. Sin embargo, continuaron en n\u00f3mina personajes de la talla de Miguel Prado, Mar\u00eda Luisa Pi\u00f1a (esposa del director art\u00edstico, Juli\u00e1n Mor\u00e1n), David Lama, Blanca Estela Pav\u00f3n, Mar\u00eda Elena de la Fuente y su esposo Enrique Quezada (futura primera voz de Los tres Diamantes), Vicente Bergmann, Raquel Moreno, Carlos de Nava, Jaime Nolla Reyes y los maestros Guillermo \u00c1lvarez y \u00c1lvarez, Evaristo Tafoya, Miguel Lerdo de Tejada Jr., y Ra\u00fal Alc\u00e1ntara.<\/p>\n<p>En 1947, una nota aparecida en el Bolet\u00edn Radiof\u00f3nico, a prop\u00f3sito del 24\u00b0 aniversario de la emisora, coment\u00f3: \u201c [\u2026] se ha dicho de la XEB que fue una cuna de artistas. Alumbr\u00f3, en efecto, valores desconocidos, alent\u00f3 a los que ya ten\u00edan notoriedad y ensanch\u00f3 ante todos ellos un campo espl\u00e9ndido de trabajo y provecho. Muchos de los cantantes, m\u00fasicos, etc., que hoy han logrado ya fama merecida, a la XEB le deben, en gran parte, o en toda, la popularidad y el dinero ganados. De este modo, XEB traz\u00f3 normas y se\u00f1al\u00f3 una escuela\u2026\u201d<\/p>\n<p>En 1950, el slogan de XEB y XEBT (onda corta), era \u201cLas Emisoras de Am\u00e9rica\u201d, ya sin alusi\u00f3n a la Compa\u00f1\u00eda Cigarrera del Buen Tono, a la que a\u00fan pertenec\u00edan. La \u201cB\u201d se ubicaba en los 1220 kilohertz de Amplitud Modulada, y transmit\u00eda con 100,000 watts, mientras que la onda corta, situada en los 9625 kilohertz, manten\u00eda una potencia de 10,000 watts efectivos en antena.<\/p>\n<p>El 1\u00b0 de noviembre de 1952, la emisora qued\u00f3 arrendada al empresario Luis Mart\u00ednez V\u00e9rtiz. Fue el tiempo en que los cronistas deportivos \u00c1ngel Fern\u00e1ndez y \u00d3scar \u201cEl r\u00e1pido\u201d Esquivel iniciaron sus actividades radiof\u00f3nicas en los micr\u00f3fonos de \u201cLas emisoras de Am\u00e9rica\u201d. El grupo de locutores en ese tiempo estaba conformado por: Melchor Maga\u00f1a, Alfonso Ameixeira, Emilio Valencia, Rub\u00e9n Santos y Guillermo Brise\u00f1o.<\/p>\n<p>Para mayo del siguiente a\u00f1o, XEB utilizaba como slogan la frase: \u201cVoz y expresi\u00f3n de M\u00e9xico\u201d, y tuvo el acierto de reunir en el programa \u201cLa Feria de la Canci\u00f3n\u201d, a un grupo de famos\u00edsimos artistas entre los que destacaron: Pedro Infante, Olga Puig, Los Churumbeles de Espa\u00f1a, El tr\u00edo Puerto Rico, Luis G. Roldan, el Tr\u00edo Calaveras, el Mariachi Vargas de Tecalitl\u00e1n, Rosa de Castilla, el Tr\u00edo Tari\u00e1curi, La Panchita y muchos m\u00e1s. Dos compa\u00f1\u00edas de teatro radiof\u00f3nico, la \u201cMar\u00eda Guerrero\u201d y la \u201cLuciano Hern\u00e1ndez\u201d, montaron las mejores obras en XEB, que llenaban los espacios program\u00e1ticos de los domingos, a las 15:30 y a las 19:30 horas, respectivamente. Adem\u00e1s, la actriz Andrea Palma figuraba en las filas art\u00edsticas de la veterana emisora.<\/p>\n<p>En 1956, XEB altern\u00f3 diversos espacios noticiosos y de m\u00fasica rom\u00e1ntica, con programas dedicados a difundir la m\u00fasica ranchera, tanto la de moda como la tradicional. Grupos y cantantes como Los Huastecos y Mar\u00eda Alejandra, se acompa\u00f1aron por el mariachi de mayor historial en esos momentos: el de Jos\u00e9 Marmolejo.<\/p>\n<p><strong>La \u00e9poca de Sistema Radi\u00f3polis.<\/strong><\/p>\n<p>En 1957, don Emilio Azc\u00e1rraga Vidaurreta adquiri\u00f3 la concesi\u00f3n de XEB, para despu\u00e9s crear la empresa \u201cRadio Sat\u00e9lite, S. A.\u201d; la cabina de transmisi\u00f3n abandon\u00f3 por primera vez el edificio del Buen Tono, para ubicarse en Ayuntamiento 54. En esta nueva etapa, se cre\u00f3 una interesante campa\u00f1a promocional, basada en caricaturas del ingenioso dibujante y cineasta Alberto Isaac.<\/p>\n<p>En marzo de 1958, se inaugur\u00f3 el Sistema Radi\u00f3polis, ubicado en Rio de la Loza 182, 2\u00ba piso, y en dicho inmueble fueron instaladas las cabinas de XEB, junto otras emisoras del grupo. Dos a\u00f1os despu\u00e9s, cuando Mario Vargas era director art\u00edstico de XEB, la emisora contaba con un renovado cuerpo de j\u00f3venes locutores, integrado por: Melquiades S\u00e1nchez Orozco, Jos\u00e9 S\u00e1nchez, Gustavo Armando \u201cEl conde\u201d Calder\u00f3n, Luis Garmendia, Jorge Kellog y Alejandro Rodr\u00edguez Mor\u00e1n \u201cEl sheriff\u201d. Este \u00faltimo tuvo dos excelentes ideas durante su breve paso por la emisora: crear del slogan \u201cLa B Grande de M\u00e9xico\u201d, que actualmente identifica a XEB, e innovar la programaci\u00f3n nocturna con el programa \u201cSerenata XEB\u201d, que desde 1960 fue uno de los espacios rom\u00e1nticos m\u00e1s escuchados de la radio, donde el p\u00fablico participaba con sus cartas y peticiones. Un dato curioso: durante 1960 el actor David Silva y el cantante Pedro Vargas, laboraron tambi\u00e9n como locutores de XEB. En ese mismo a\u00f1o, se cre\u00f3 el concepto titulado \u201cNarraciones Radi\u00f3polis\u201d, que incluy\u00f3 las radionovelas \u201cEl conde de Montecristo\u201d y \u201cEl corsario negro\u201d, entre otras, narradas por Jorge Kellog, donde figur\u00f3 como actor principal Guillermo Portillo Acosta.<\/p>\n<p>En 1962, cerr\u00f3 sus operaciones la emisora de onda corta XEBT, despu\u00e9s de 29 a\u00f1os de actividades. Entre 1962 y 1964, las emisoras que formaban parte de Radi\u00f3polis se reunieron en un concepto nominado: \u201cLos tres puntos de oro de la radio\u201d (XEB, XEQ y XEDF), al que despu\u00e9s se sum\u00f3 Radio 660, XERPM, para formar los \u201ccuatro puntos\u201d; en 1965, se constituyeron \u201cLos cinco puntos de oro\u201d cuando se integr\u00f3 la emisora XEN. Los que participaron en la \u201cB\u201d de estos tiempos, fueron: Manuel Camacho, Salvador Rosiles Razo, Ram\u00f3n R\u00edos, Pepe Garc\u00e9s y Eduardo Linares<\/p>\n<p><strong>Los tiempos de Radio F\u00f3rmula.<\/strong><\/p>\n<p>Para 1967, la concesi\u00f3n de XEB fue adquirida por Rogerio Azc\u00e1rraga Madero, con las que integr\u00f3 el Grupo ORO. Las cabinas se trasladaron al inmueble ubicado en Dr. Rio de la Loza y Avenida Cuauht\u00e9moc. Alrededor de 1975, al cambiar la raz\u00f3n social por Radio F\u00f3rmula, todas las emisoras fueron enumeradas, conforme a su posici\u00f3n en el cuadrante; a XEB le asignaron el nombre de \u201cRadio tres\u201d. Durante la etapa en que XEB perteneci\u00f3 a Radio F\u00f3rmula, algunos locutores que identificaron la emisora, fueron: Carlos Fuentes, Jorge Kellog, Armando R\u00e9ndiz y Jos\u00e9 V\u00edctor Rodr\u00edguez, quienes continuaron en nuestros micr\u00f3fonos por muchos a\u00f1os.<\/p>\n<p>El 21 de diciembre de 1978, el manejo de XEB y otras dos estaciones de Radio F\u00f3rmula (XERPM y XEMP), fue asumido por el gobierno federal. Este hecho hist\u00f3rico defini\u00f3, cuatro a\u00f1os m\u00e1s tarde, la creaci\u00f3n de un organismo p\u00fablico descentralizado como titular de dichas emisoras. Entre tanto, para administrar XEB, a partir de 1979 se cre\u00f3 la concesionaria Compa\u00f1\u00eda Nacional de Radiodifusi\u00f3n, S. A., coordinada por la Direcci\u00f3n General de Radio, Televisi\u00f3n y Cinematograf\u00eda de la Secretar\u00eda de Gobernaci\u00f3n. A pesar de los cambios, sus cabinas continuaron en Dr. Rio de la Loza y Av. Cuauht\u00e9moc.<\/p>\n<p><strong>Los \u00faltimos 31 a\u00f1os: una nueva y creativa etapa.<\/strong><\/p>\n<p>El 23 mes de marzo de 1983 inici\u00f3 sus actividades el Instituto Mexicano de la Radio con las emisoras que pertenecieron a Radio F\u00f3rmula (XEB, XERPM y XEMP), adem\u00e1s de una estaci\u00f3n en Frecuencia Modulada, la XHOF. La naciente instituci\u00f3n oficial dio inicio a una etapa importante para la radio de estado, en lo que se refiere a la difusi\u00f3n de programas de inter\u00e9s cultural y social.<\/p>\n<p>A partir de ese a\u00f1o, se utiliz\u00f3 un nuevo slogan: \u201cXEB, Radio M\u00e9xico. La estaci\u00f3n nacional y familiar del Instituto Mexicano de la Radio\u201d. Sus cabinas abandonaron el inmueble de Rio de la Loza, para situarse en Margaritas # 18, colonia Florida. Para el mes de mayo, el experimentado Rafael Cardona Lynch, fue designado gerente de la emisora.<\/p>\n<p>Desde mediados de 1983, XEB implement\u00f3 una estrategia para reforzar la imagen de mexicanidad, con la transmisi\u00f3n exclusiva de m\u00fasica de autores nacionales, en todos los g\u00e9neros y con int\u00e9rpretes mexicanos o extranjeros. Adem\u00e1s, las fastuosas celebraciones de aniversario, que desde tres d\u00e9cadas atr\u00e1s no se realizaban, volvieron a festejarse el d\u00eda 23 de septiembre, ya que resultaba dif\u00edcil hacer una celebraci\u00f3n empatada con los d\u00edas patrios (15 o 16 de septiembre). Tambi\u00e9n, se implement\u00f3 la \u201cbarra femenina\u201d con el programa \u201cMujer\u201d, concepto que se mantiene hasta la fecha con el nombre de \u201cHabla con ellas\u201d.<\/p>\n<p>Algunos programas destacados de XEB durante el lapso 1983-1989, fueron los siguientes: \u201cComentando el noticiario\u201d, \u201cForo obrero\u201d, \u201cHistoria musical de M\u00e9xico\u201d, \u201cLa B en el campo\u201d, \u201cLa canci\u00f3n mexicana embajadora ante el mundo\u201d, \u201cL\u00ednea nocturna\u201d (programa de servicio y asistencia al radioescucha), \u201cMujer\u201d (barra matutina), \u201cPalabra y m\u00fasica de M\u00e9xico\u201d, \u201cSerenata\u201d, \u201cTardes rom\u00e1nticas\u201d (con artistas en vivo), \u201cUna hora con Agust\u00edn Lara\u201d y \u201cVoces y guitarras\u201d (uno de los favoritos del p\u00fablico radioescucha).<\/p>\n<p>En 1987, una mujer ocup\u00f3 por vez primera un puesto como locutora en XEB: Olga Romero Gamero. A partir del a\u00f1o 2001, se integraron Claudia Ram\u00edrez, Margarita Gonz\u00e1lez, Ivonne Castillo (quien contin\u00faa en la emisora) y Susana Rodr\u00edguez. En cuanto a las comentaristas, el n\u00famero resulta mucho m\u00e1s numeroso, ya que desde la creaci\u00f3n del IMER, la mujer comenz\u00f3 a ganar terreno en los programas de contenido; aunque la lista es muy grande, podr\u00edamos destacar a: Carlota Villagr\u00e1n, Irene Moreno, Micheline Kinery, F\u00e1tima Ibarrola, Laura Gamiz, A\u00edda del Rio, Julia Rodr\u00edguez, Lourdes Diaque, Martha de la Lama, Adriana P\u00e9rez Ca\u00f1edo, Rita Abreu, Lidia P\u00e9rez, Nora Salda\u00f1a, Laura Blum, Ver\u00f3nica Medina, Lilia Silvia Hern\u00e1ndez, Patricia de Anda Hermoso, Ver\u00f3nica Ortiz, Marisa Escribano y Luz Mar\u00eda Meza, entre otras.<\/p>\n<p>En 1988, XEB redact\u00f3 sus objetivos de trabajo en un documento informativo, donde destaca su labor para \u201cpreservar, difundir y fortalecer nuestra aut\u00e9ntica m\u00fasica popular y fortalecer su presencia en las nuevas generaciones [\u2026] Tambi\u00e9n, se evit\u00f3 la transmisi\u00f3n de programas de mal gusto, comentarios inconvenientes y desde luego anuncios de bebidas alcoh\u00f3licas, cigarrillos o alimentos chatarra&#8230;\u201d Para esa fecha, la gerencia de XEB era ocupada por el sr. Heberto P\u00e9rez. El grupo de locutores estaba integrado por: Ram\u00f3n R\u00edos Hern\u00e1ndez, Jos\u00e9 Garc\u00e9s, Alfonso Zacar\u00edas, Guillermo Mej\u00eda Llosas y Jos\u00e9 Victor Rodr\u00edguez.<\/p>\n<p>En la lista de programas transmitidos durante 1991 y 1993, se observa un af\u00e1n por enriquecer y diversificar todos los horarios, siempre bajo un concepto cultural; algunos t\u00edtulos son: \u201cLas canciones m\u00e1s bonitas de ayer y hoy\u201d, \u201cHistoria musical de M\u00e9xico\u201d, \u201cLa hora del futbol\u201d, \u201cMujer\u201d, \u201cLa B en el campo\u201d, \u201cPanorama cultural\u201d, \u201cTeatrofilia\u201d, \u201cEl noticiario\u201d, \u201cLa magia del cuento\u201d y \u201cPuro filin\u201d, entre otros.<\/p>\n<p>Entre los programas transmitidos por XEB, de 1993 a 1994, figuran los siguientes: \u201cAbriendo puertas\u201d, \u201cDr. Federico Ortiz Quesada\u201d, \u201cGrandes de la canci\u00f3n mexicana\u201d, \u201cHistoria Musical de M\u00e9xico\u201d \u201cLo que lee el que vive\u201d, \u201cMujer\u201d, \u201cViva la radio\u201d, \u201cEl estudio de Roberto Jord\u00e1n\u201d, \u201cManzanero a trav\u00e9s de su m\u00fasica\u201d, \u201cM\u00e9xico frente al cambio\u201d, \u201cY nosotros los ni\u00f1os qu\u00e9?\u201d, \u201cLatinoam\u00e9rica rom\u00e1ntica\u201d etc. En 1993 inici\u00f3 el noticiario Antena Radio, actualmente uno de los m\u00e1s longevos de la radio mexicana.<\/p>\n<p>Desde mediados de 1994 se increment\u00f3 la programaci\u00f3n musical en XEB, con el concepto de m\u00fasica rom\u00e1ntica en espa\u00f1ol y boleros tanto cl\u00e1sicos como en modernas versiones. La gerente en ese y los siguientes a\u00f1os fue Mar\u00eda Guadalupe Hurtado Trevi\u00f1o. Nuevamente, volvi\u00f3 a utilizarse el slogan tradicional \u201cXEB, La B Grande de M\u00e9xico\u201d, instituido desde 1960.<\/p>\n<p>Programas destacados en 1996, fueron: \u201cA mi tierra mexicana\u201d, \u201cBuenos d\u00edas con la B\u201d, \u201cConcursando y ganando con la B\u201d, \u201cInmortales de la B\u201d, \u201cLa hora rom\u00e1ntica de Jos\u00e9 Jos\u00e9\u201d, \u201cRevista de opini\u00f3n\u201d, \u201c Serenata XEB\u201d, \u201cUna voz en la noche\u201d, \u201cVoces y guitarras\u201d, etc.<\/p>\n<p>La imagen cultural, de servicio y entretenimiento que ofreci\u00f3 XEB durante el fin de milenio y el inicio del siglo XXI, se manifest\u00f3 con programas de contenido, radionovelas y emisiones musicales cuyo t\u00edtulo manifiesta el af\u00e1n incesante por lograr una radio con calidad. Escogiendo al azar, en el lapso de 1997 a 1999, se enlistan los siguientes programas: \u201cAmanecer campesino\u201d, \u201c\u00c9ramos 6\u201d, \u201cIslas Mar\u00edas\u201d (radionovela), \u201cLa ciudad del crimen\u201d, \u201cGaler\u00eda del recuerdo\u201d \u201cAn\u00e1lisis taurino&#8221;, \u201cHablemos de salud\u201d y \u201cPresencia del siglo\u201d. Del a\u00f1o 2000 al 2001, XEB transmiti\u00f3, entre muchos otros, los siguientes programas: \u201cRevista de opini\u00f3n\u201d (con Pedro Ferriz Santacruz y Alfredo Ruiz del Rio), \u201cDesde mi tierra Yucat\u00e1n\u201d, \u201cF\u00e1tima directo\u201d, \u201cLa voz de una mujer\u201d, \u201cPor los andenes de la cultura\u201d, \u201cPrimera llamada\u201d, \u201cD\u00edas de contar\u201d, \u201cM\u00e9xico a la vista\u201d y \u201cPor la vereda\u201d (con Benito Romo de Vivar).<\/p>\n<p>En el lapso de 2002 a 2004, el perfil musical se orient\u00f3 hacia la balada, el bolero y la m\u00fasica pop; algunos programas destacados fueron: \u201cAlma de M\u00e9xico\u201d, \u201cCaf\u00e9 encuentros\u201d, \u201cC\u00f3mo la B\u201d, \u201cCon B de bolero\u201d, \u201cCon la B ganas\u201d, \u201cExplorando\u201d, \u201cHablemos de cine\u201d, \u201cImpacto deportivo\u201d, \u201cLos pasos de Cuevas\u201d (con Jos\u00e9 Luis Cuevas), \u201cLa otra opini\u00f3n\u201d, \u201cNoticiario Radio Francia\u201d, \u201cPalabras al o\u00eddo\u201d, \u201cSobre ruedas\u201d, \u201cSones y danzones\u201d, \u201cUn poema hecho canci\u00f3n\u201d, etc. Durante el a\u00f1o 2003, el slogan tradicional de XEB fue \u201cXEB, M\u00e1s Grande que Nunca\u201d, y su propuesta musical se bas\u00f3 en el bolero, la balada moderna y la canci\u00f3n pop. En esas fechas, \u00c1ngel Dehesa Christlieb era el gerente de la emisora, cargo que anteriormente ocup\u00f3 Santiago Ibarra.<\/p>\n<p>En marzo de 2005, se reestructur\u00f3 la programaci\u00f3n para mantener el equilibrio entre los programas de contenido y los musicales. La nueva imagen tuvo por nombre: \u201cXEB, la B Grande de M\u00e9xico, El Buen Tono de la Radio\u201d, parafraseando el slogan original de la emisora. Se crearon programas musicales contextualizados, como: \u201cCoraz\u00f3n urbano\u201d, \u201cGuitarra y fandango\u201d, \u201cEl rinconcito del danz\u00f3n\u201d, \u201cSones y canciones\u201d, \u201cOye mi canci\u00f3n\u201d, etc., que alternaron con emisiones de orientaci\u00f3n y servicio, tales como: \u201cPor la vereda\u201d, \u201cHabla con ellas\u201d, \u201cNo est\u00e1s solo, cuentas con nosotros\u201d y \u201cExplorando\u201d, entre otros. Jes\u00fas Flores y Escalante ocup\u00f3 en ese a\u00f1o la gerencia de la emisora.<\/p>\n<p>En 2005, la programaci\u00f3n musical matutina de s\u00e1bados y domingos se dise\u00f1\u00f3 para difundir las obras de nuestros autores vern\u00e1culos, con el t\u00edtulo \u201cRomance y tradici\u00f3n\u201d, que dio cabida a la canci\u00f3n ranchera, el son jarocho, el huapango, la trova yucateca y otros g\u00e9neros que hoy integran el espacio que se llama \u201cM\u00fasica con tradici\u00f3n\u201d. De este modo, XEB retom\u00f3 su papel de difusora de la canci\u00f3n tradicional mexicana y de las expresiones culturales que integran nuestra identidad.<\/p>\n<p>A partir de 2007, nuevos programas de contenido se sumaron a la programaci\u00f3n de XEB: \u201cKilo por kilo\u201d, \u201cEntre nos\u201d, \u201cCr\u00f3nica citadina\u201d, \u201cVivir y morir en s\u00e1bado\u201d, \u201cBaile por la salud\u201d, \u201cNo canto pero me encanta\u201d, \u201cLidiando juntos\u201d y otros que se combinaron con los espacios musicales, integrados por m\u00fasica de cat\u00e1logo en diversos g\u00e9neros.<\/p>\n<p><strong>La se\u00f1al digital, en espera de los a\u00f1os futuros.<\/strong><\/p>\n<p>El 17 de septiembre de 2012, el IMER dio un paso hist\u00f3rico en la radio mexicana, al inaugurar nueve se\u00f1ales digitales; una de ellas fue asignada a XEB, que desde ese momento comenz\u00f3 a transmitir simult\u00e1neamente en Frecuencia Modulada, a trav\u00e9s del canal HD2 del 94.5. En diciembre de ese a\u00f1o, Jos\u00e9 Pablo Due\u00f1as ocup\u00f3 la gerencia de la emisora.<\/p>\n<p>En febrero de 2013, iniciaron diversos espacios musicales, abriendo paso a conceptos y g\u00e9neros de inter\u00e9s hist\u00f3rico. Algunos t\u00edtulos son: \u201cA 78 rpm\u201d, \u201cCorte y suena, la m\u00fasica en el cine mexicano\u201d, \u201cA media luz\u201d, \u201cPor siempre XEB\u201d y \u201cAmanece\u201d. Un a\u00f1o m\u00e1s tarde, nuevos programas de contenido enriquecieron la alternancia con la f\u00f3rmula musical, basada en el cat\u00e1logo rom\u00e1ntico y bailable de las cinco \u00faltimas d\u00e9cadas; actualmente, integran la carta program\u00e1tica de La B Grande de M\u00e9xico emisiones de la categor\u00eda de \u201cHabla con ellas\u201d (12 a\u00f1os al aire), el programa de concurso \u201cLas nuevas voces del bolero\u201d, \u201cConversaciones sobre historia\u201d, \u201cAlternativas sin barreras\u201d, Por la vereda\u201d, \u201cKilo por kilo\u201d, \u201cLa Suprema Corte cerca de ti\u201d e \u201cHistoria de las revoluciones de M\u00e9xico\u201d, entre otras.<\/p>\n<p>Los locutores que integran la plantilla de XEB en 2014, son: Ivonne Castillo, Alfonso Zacar\u00edas, Ram\u00f3n Romero, Manuel S\u00e1nchez y Mart\u00ednez, Ricardo Zamora y Francisco Javier Orozco.<\/p>\n<p>La historia de XEB, lo mismo que las emisoras del Instituto Mexicano de la Radio, contin\u00faa escribi\u00e9ndose con may\u00fasculas. Cumple su funci\u00f3n de radio p\u00fablica para beneficio de la sociedad, como afirma el slogan institucional: \u201cproducimos sonidos y los transformamos en ideas\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El inicio El 16 de junio de 1923, se inaugur\u00f3 la Primera Feria Internacional de la Radio, promovida por la Liga Central Mexicana de Radio, para mostrar al p\u00fablico los beneficios de una industria naciente. Como actividad promocional, la Compa\u00f1\u00eda Cigarrera del Buen Tono, S. A., lanz\u00f3 a la venta una marca de cigarrillos \u201cRadio\u201d&hellip;<\/p>\n","protected":false},"author":17,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"wp_popup_display_lightbox":0,"wp_popup_suppress":"","wp_popup_trigger":"","wp_popup_trigger_amount":0,"wp_popup_disable_on_mobile":false,"footnotes":""},"class_list":["post-1816","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/pages\/1816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/comments?post=1816"}],"version-history":[{"count":0,"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/pages\/1816\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.imer.mx\/xeb\/wp-json\/wp\/v2\/media?parent=1816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}