{"id":27902,"date":"2018-11-22T16:30:59","date_gmt":"2018-11-22T22:30:59","guid":{"rendered":"https:\/\/www.imer.mx\/micrositios\/?p=27902"},"modified":"2018-12-14T15:17:41","modified_gmt":"2018-12-14T21:17:41","slug":"lanzamiento-del-album-super-trouper-de-abba","status":"publish","type":"post","link":"https:\/\/www.imer.mx\/micrositios\/lanzamiento-del-album-super-trouper-de-abba\/","title":{"rendered":"Lanzamiento del \u00e1lbum &#8220;Super Trouper&#8221; de ABBA"},"content":{"rendered":"<p><strong>22 de noviembre 1980<\/strong><\/p>\n<p>Liderado por el \u00e9xito internacional\u00a0\u201cThe Winner Takes It All\u201d, Super Trouper fue el s\u00e9ptimo \u00e1lbum del grupo en el Reino Unido publicado \u00a0por Polar Music.\u00a0Tambi\u00e9n fue el \u00e1lbum m\u00e1s vendido en Gran Breta\u00f1a, llegando al n\u00famero 1\u00b0 el 22 de noviembre de 1980. El \u00e1lbum ha sido reeditado en forma remasterizada digitalmente cuatro veces;\u00a0primero en 1997, luego en 2001, nuevamente en 2005 como parte del set de The Complete Studio Recordings y como Deluxe Edition (que contiene un DVD adicional) en 2011.<\/p>\n<p>Probablemente debido a la reacci\u00f3n violenta de la discoteca de la \u00e9poca, el \u00e1lbum vio a ABBA regresando a un sonido pop m\u00e1s directo, a diferencia del \u00e1lbum Voulez-Vous anterior (y notablemente m\u00e1s orientado hacia la danza).\u00a0El \u00e1lbum se cerr\u00f3 con\u00a0\u201cThe Way Old Friends Do\u201d, que se grab\u00f3 en vivo un a\u00f1o antes durante su gira de conciertos de 1979.\u00a0Aunque no se lanz\u00f3 como single con este \u00e1lbum, la canci\u00f3n se lanz\u00f3 posteriormente como single en 1992 para promocionar el recopilatorio More ABBA Gold: More ABBA Hits.\u00a0La canci\u00f3n fue luego cubierta por The Alexander Brothers, The Kingston Trio, Philomena Begley y Faryl Smith.<\/p>\n<p>Con s\u00f3lo dos canciones descartadas y un tiempo de grabaci\u00f3n de s\u00f3lo nueve meses,\u00a0Super Trouper\u00a0fue uno de los \u00e1lbumes que ABBA complet\u00f3 m\u00e1s r\u00e1pidamente. El trabajo en el nuevo LP hab\u00eda comenzado en enero, cuando Bj\u00f6rn y Benny viajaron a\u00a0Barbados\u00a0en un viaje para inspirarse, tal como lo hab\u00edan hecho un a\u00f1o atr\u00e1s, cuando viajaron a\u00a0Miami\u00a0y grabaron &#8220;Voulez Vous&#8221;. De esta experiencia se obtuvieron cinco nuevas canciones que se comenzaron a grabar el\u00a04 de febrero\u00a0de\u00a01980: &#8220;Hold Me Close&#8221;, &#8220;\u00c4ntligen Krig&#8221;, &#8220;Daddy Don\u2019t Get Drunk On Christmas Day&#8221;, &#8220;Esses Vad Det Sv\u00e4nger N\u00e4r Man Spelar Jazz&#8221; y &#8220;Elaine&#8221;, esta \u00faltima lanzada como lado B de &#8220;The Winner Takes It All&#8221; y posteriormente incluida en el \u00e1lbum como bonus track. Despu\u00e9s de comenzar estas pistas, ABBA viaja a\u00a0Jap\u00f3n\u00a0donde realizan su\u00a0\u00faltima gira.<\/p>\n<p>El\u00a09 de abril\u00a0&#8220;Hold Me Close&#8221; se convertir\u00eda en &#8220;Andante, Andante&#8221; y \u00c4ntligen Krig&#8221; en &#8220;The Piper&#8221;.&#8221;Daddy Don\u2019t Get Drunk On Christmas Day&#8221; hab\u00eda sido planeada para un musical que ten\u00eda lugar en la v\u00edspera de a\u00f1o nuevo, y aunque Bj\u00f6rn y Benny nunca pudieron concretar esa idea la canci\u00f3n fue grabada ese mismo 9 de abril bajo el t\u00edtulo de &#8220;Happy New Year&#8221;.\u200b El\u00a024 de abril, de la pista &#8220;Esses Vad Det Sv\u00e4nger N\u00e4r Man Spelar Jazz&#8221; surgir\u00eda &#8220;On and On and On&#8221;, lanzada como sencillo en algunos pa\u00edses.<\/p>\n<p>El\u00a02 de junio\u00a0comienzan los trabajos en &#8220;The Story Of My Life&#8221;. Al d\u00eda siguiente, el\u00a03 de junio, se graba el demo &#8220;Burning My Bridges&#8221;, no publicado hasta\u00a01994\u00a0en el\u00a0ABBA Undeleted. El\u00a04 de junio\u00a0Frida graba el tema &#8220;Our Last Summer&#8221;, una balada inspirada en un romance de Bj\u00f6rn en Francia cuando era m\u00e1s joven. El\u00a06 de junio\u00a0se le agrega la letra a la pista &#8220;The Story Of My Life&#8221;, dando lugar al primer sencillo del \u00e1lbum, &#8220;The Winner Takes It All&#8221;, cuya letra estuvo inspirada en el divorcio de Bj\u00f6rn y Agnetha.<\/p>\n<p>Las sesiones de grabaci\u00f3n se reanudan el\u00a08 de septiembre\u00a0cuando se graba &#8220;Piccolino&#8221;, t\u00edtulo previo de &#8220;Me And I&#8221;. El\u00a09 de septiembre, Agnetha pone su voz en la pista\u00a0dance\u00a0&#8220;Yarrafat&#8221;, para convertirse en &#8220;Lay All Your Love On Me&#8221;, tercer sencillo del \u00e1lbum en algunos pa\u00edses. Ese mismo d\u00eda, tiene lugar la grabaci\u00f3n de &#8220;Put On Your White Sombrero&#8221;, canci\u00f3n que no fue publicada hasta\u00a01994, en el box set\u00a0Thank you for the Music y que posteriormente se incluir\u00eda como bonus track del \u00e1lbum.<\/p>\n<p>El\u00a03 de octubre, s\u00f3lo unos d\u00edas antes de la sesi\u00f3n de fotos para la portada del \u00e1lbum, Bj\u00f6rn y Benny hab\u00edan comenzado a trabajar con la pista de &#8220;Blinka Lilla Stj\u00e4rna&#8221;, que con la voz de Frida pas\u00f3 a ser &#8220;Super Trouper&#8221;, segundo sencillo del \u00e1lbum.\u200b Ya como \u00faltima pista, el grupo decidi\u00f3 incluir un tema\u00a0 en vivo: &#8220;The Way Old Friends Do&#8221;, una canci\u00f3n presentada durante su\u00a0tour de 1979. El\u00a08 de octubre\u00a0se retoca la grabaci\u00f3n de su concierto en la\u00a0Wembley Arena\u00a0y con esto finalizan las sesiones de grabaci\u00f3n del \u00e1lbum.No obstante, en octubre de\u00a01980, semanas antes del lanzamiento del \u00e1lbum, Frida y Agnetha graban las canciones &#8220;Andante, Andante&#8221; y &#8220;Felicidad&#8221;, que sustituir\u00e1n a sus versiones en ingl\u00e9s en pa\u00edses de habla hispana, y que ser\u00edan publicados como canciones promocionales en\u00a0Sudam\u00e9rica.<\/p>\n<p>Super Trouper\u00a0fue publicado por primera vez en\u00a0Escandinavia\u00a0el\u00a03 de noviembre de\u00a01980, bajo el sello de Polar Music. En pa\u00edses hispanos, los temas &#8220;Andante, Andante&#8221; y &#8220;Happy New Year&#8221; fueron sustituidos por sus versiones en espa\u00f1ol. En el\u00a0Reino Unido\u00a0fue lanzado un box set de edici\u00f3n especial, que conten\u00eda el LP, un folder con la imagen del grupo, el libro\u00a0\u201cABBA For The Record\u201d\u00a0de John Trobler y un p\u00f3ster con la portada del disco.<\/p>\n<p>Super Trouper\u00a0fue recibido bien por la mayor parte de las cr\u00edticas. La mayor\u00eda de ellas resaltan el hecho de que ABBA deja atr\u00e1s la m\u00fasica disco.\u200b En la revista\u00a0Rolling Stone, Stephen Holden menciona: &#8220;Super Trouper\u00a0es la lecci\u00f3n de m\u00fasica m\u00e1s atractiva de ABBA desde\u00a0Arrival&#8221;, d\u00e1ndole s\u00f3lo dos estrellas de cinco.\u200b Otros cr\u00edticos hacen notar que el \u00e1lbum tiene buenas canciones, pero tambi\u00e9n malas. Adri\u00e1n Denning resalta:\u00a0Super Trouper\u00a0es todav\u00eda fuerte despu\u00e9s de todo, las buenas canciones llevan al \u00e1lbum entero a un nivel que ciertamente podemos llamar bueno&#8221;, al mismo tiempo le da siete estrellas y media de diez.Finalmente, George Starostin escribe sobre el \u00e1lbum: &#8220;Suena bien. Menos disco, m\u00e1s ruido. Menos ruido, mejores canciones pop. Pero no lo suficiente&#8221; y les da ocho estrellas de diez clasific\u00e1ndolo como &#8220;S\u00f3lo muy bueno&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liderado por el \u00e9xito internacional\u00a0\u201cThe Winner Takes It All\u201d, Super Trouper fue el s\u00e9ptimo \u00e1lbum del grupo en el Reino Unido publicado \u00a0por Polar Music.\u00a0Tambi\u00e9n fue el \u00e1lbum m\u00e1s vendido en Gran Breta\u00f1a, llegando al n\u00famero 1\u00b0 el 22 de noviembre de 1980.<\/p>\n","protected":false},"author":141,"featured_media":27903,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_popup_display_lightbox":0,"wp_popup_suppress":"","wp_popup_trigger":"","wp_popup_trigger_amount":0,"wp_popup_disable_on_mobile":false,"footnotes":""},"categories":[190],"tags":[],"class_list":["post-27902","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-momentos-musica","category-190","description-off"],"_links":{"self":[{"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/posts\/27902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/comments?post=27902"}],"version-history":[{"count":0,"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/posts\/27902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/media\/27903"}],"wp:attachment":[{"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/media?parent=27902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/categories?post=27902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.imer.mx\/micrositios\/wp-json\/wp\/v2\/tags?post=27902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}